{"id":17536,"date":"2026-04-21T18:21:24","date_gmt":"2026-04-21T16:21:24","guid":{"rendered":"https:\/\/ces.gob.gt\/?p=17536"},"modified":"2026-04-21T19:10:57","modified_gmt":"2026-04-21T17:10:57","slug":"participacion-del-ces-guatemala-en-el-taller-de-induccion-para-nuevos-consejeros-del-ces-de-republica-dominicana","status":"publish","type":"post","link":"https:\/\/ces.gob.gt\/index.php\/2026\/04\/21\/participacion-del-ces-guatemala-en-el-taller-de-induccion-para-nuevos-consejeros-del-ces-de-republica-dominicana\/","title":{"rendered":"Participaci\u00f3n del CES Guatemala en el Taller de Inducci\u00f3n para Nuevos Consejeros del CES de Rep\u00fablica Dominicana"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17536\" class=\"elementor elementor-17536\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18507fa e-flex e-con-boxed e-con e-parent\" data-id=\"18507fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5931e58 elementor-widget elementor-widget-text-editor\" data-id=\"5931e58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"118\" data-end=\"791\">El <strong data-start=\"121\" data-end=\"178\">Consejo Econ\u00f3mico y Social de la Rep\u00fablica Dominicana<\/strong> desarroll\u00f3 los d\u00edas <strong data-start=\"199\" data-end=\"227\">10 y 11 de abril de 2026<\/strong>, el <strong data-start=\"272\" data-end=\"318\">Taller de Inducci\u00f3n para Nuevos Consejeros<\/strong>, dirigido a los consejeros titulares y suplentes designados por las organizaciones de los sectores social, laboral y empresarial para el per\u00edodo 2025-2029. La actividad tuvo como prop\u00f3sito fortalecer el conocimiento sobre el funcionamiento, principios, marco institucional y rol del CES dominicano como \u00f3rgano constitucional de concertaci\u00f3n social, as\u00ed como propiciar una mayor cohesi\u00f3n entre sus integrantes para el cumplimiento de sus responsabilidades dentro del Pleno.<\/p><p data-start=\"793\" data-end=\"1715\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-17541\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-100930-300x161.png\" alt=\"\" width=\"600\" height=\"323\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-100930-300x161.png 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-100930-1024x551.png 1024w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-100930-768x413.png 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-100930.png 1231w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>En el m\u00f3dulo dedicado al <strong data-start=\"818\" data-end=\"843\">alcance internacional<\/strong>, particip\u00f3 a distancia el <strong data-start=\"870\" data-end=\"908\">Lic. Bernardo Jes\u00fas L\u00f3pez Figueroa<\/strong>, Secretario T\u00e9cnico del <strong data-start=\"933\" data-end=\"976\">Consejo Econ\u00f3mico y Social de Guatemala<\/strong>, con la exposici\u00f3n titulada <strong data-start=\"1005\" data-end=\"1164\">\u201cTrabajo en red, di\u00e1logo social en tiempos de incertidumbre: la Red Latinoamericana de Consejos Econ\u00f3micos y Sociales e Instituciones Similares \u2014CESISALC\u2014\u201d<\/strong>. Su intervenci\u00f3n se realiz\u00f3 en representaci\u00f3n del <strong data-start=\"1215\" data-end=\"1315\">CES Guatemala, instituci\u00f3n que actualmente ostenta la Presidencia Pro Tempore de la Red CESISALC<\/strong>, y destac\u00f3 la importancia del trabajo en red como respuesta estrat\u00e9gica ante contextos de incertidumbre, transformaci\u00f3n social y desaf\u00edos regionales. Asimismo, subray\u00f3 el valor de la cooperaci\u00f3n horizontal, el intercambio de buenas pr\u00e1cticas, el aprendizaje continuo y el fortalecimiento institucional entre los Consejos Econ\u00f3micos y Sociales e instituciones similares de Am\u00e9rica Latina y el Caribe.<\/p><p data-start=\"1717\" data-end=\"2418\">Durante las jornadas tambi\u00e9n participaron expositores nacionales e internacionales que abordaron temas vinculados con la historia y evoluci\u00f3n de los espacios de di\u00e1logo social, el marco legal e institucional del CES dominicano, su estructura y funcionamiento interno, la incidencia en pol\u00edticas p\u00fablicas, las t\u00e9cnicas de negociaci\u00f3n y construcci\u00f3n de consensos, as\u00ed como la \u00e9tica, representatividad y responsabilidad de los consejeros. En el componente internacional se compartieron, adem\u00e1s, experiencias relacionadas con la <strong data-start=\"2242\" data-end=\"2253\">AICESIS<\/strong>, la <strong data-start=\"2258\" data-end=\"2274\">Red CESISALC<\/strong> y la <strong data-start=\"2280\" data-end=\"2291\">RICESIS<\/strong>, con el objetivo de ampliar la comprensi\u00f3n sobre la proyecci\u00f3n regional e internacional de los Consejos Econ\u00f3micos y Sociales.<img decoding=\"async\" class=\"aligncenter wp-image-17542 size-large\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-101219-1024x427.png\" alt=\"\" width=\"1024\" height=\"427\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-101219-1024x427.png 1024w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-101219-300x125.png 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-101219-768x320.png 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-21-101219.png 1206w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p data-start=\"2420\" data-end=\"2942\" data-is-last-node=\"\" data-is-only-node=\"\">La participaci\u00f3n del CES Guatemala en este espacio reafirma el papel de la <strong data-start=\"2495\" data-end=\"2511\">Red CESISALC<\/strong> como plataforma regional para promover el di\u00e1logo social institucionalizado, facilitar la cooperaci\u00f3n t\u00e9cnica entre pa\u00edses y articular aprendizajes frente a desaf\u00edos comunes. Desde la Presidencia Pro Tempore de la Red, el CES Guatemala contribuye a fortalecer los v\u00ednculos entre instituciones hom\u00f3logas de la regi\u00f3n y a proyectar el di\u00e1logo social como una herramienta clave para la gobernanza democr\u00e1tica, inclusiva y sostenible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89b2340 e-flex e-con-boxed e-con e-parent\" data-id=\"89b2340\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7b7b57 uael-img-grid__column-4 uael-img-grid-tablet__column-3 uael-img-grid-mobile__column-2 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"e7b7b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_columns&quot;:&quot;4&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;gallery_columns_mobile&quot;:&quot;2&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;images_valign&quot;:&quot;flex-start&quot;}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption- uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-grid-wrap uael-img-grid-masonry-wrap\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02726-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02726-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17543\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02726-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02726-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02726-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02626-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02626-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17544\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02626-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02626-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02626-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02526-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02526-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17545\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02526-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02526-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02526-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02426-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02426-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17546\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02426-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02426-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02426-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02326-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02326-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17547\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02326-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02326-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02326-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02126-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02126-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17548\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02126-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02126-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02126-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-7\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02026-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02026-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17549\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02026-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02026-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/02026-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-8\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01926-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01926-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17550\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01926-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01926-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01926-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-9\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01826-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01826-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17551\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01826-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01826-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01826-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-10\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01726-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01726-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17552\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01726-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01726-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01726-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-11\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01626-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01626-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17553\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01626-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01626-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01626-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-12\"><div class=\"uael-grid-item-content\"><a class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\" target=\"_blank\" rel=\"dofollow\" href=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01526-taller-induccion-10y11.04.26.jpg\" data-elementor-open-lightbox=\"no\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01526-taller-induccion-10y11.04.26-300x160.jpg\" class=\"attachment-medium size-medium wp-image-17554\" alt=\"\" srcset=\"https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01526-taller-induccion-10y11.04.26-300x160.jpg 300w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01526-taller-induccion-10y11.04.26-768x411.jpg 768w, https:\/\/ces.gob.gt\/wp-content\/uploads\/2026\/04\/01526-taller-induccion-10y11.04.26.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En ella el Lic. Bernardo L\u00f3pez abord\u00f3 la importancia del trabajo en red como una herramienta estrat\u00e9gica para fortalecer el di\u00e1logo social, compartir aprendizajes institucionales y articular respuestas regionales ante contextos marcados por la incertidumbre, la transformaci\u00f3n social y los desaf\u00edos comunes de Am\u00e9rica Latina y el Caribe.<\/p>\n","protected":false},"author":4,"featured_media":17540,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/posts\/17536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/comments?post=17536"}],"version-history":[{"count":6,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/posts\/17536\/revisions"}],"predecessor-version":[{"id":17560,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/posts\/17536\/revisions\/17560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/media\/17540"}],"wp:attachment":[{"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/media?parent=17536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/categories?post=17536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ces.gob.gt\/index.php\/wp-json\/wp\/v2\/tags?post=17536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}